{"id":502456,"date":"2008-01-01T00:00:00","date_gmt":"2008-01-01T00:00:00","guid":{"rendered":"https:\/\/www.teachersparadise.com\/co\/p\/free-spirit-publishing-germs-are-not-for-sharing-best-behavior-by-elizabeth-verdick-paperback-fre1575421976\/"},"modified":"2021-08-07T15:41:50","modified_gmt":"2021-08-07T19:41:50","slug":"free-spirit-publishing-germs-are-not-for-sharing-best-behavior-by-elizabeth-verdick-paperback-fre1575421976","status":"publish","type":"product","link":"https:\/\/www.teachersparadise.com\/co\/p\/free-spirit-publishing-germs-are-not-for-sharing-best-behavior-by-elizabeth-verdick-paperback-fre1575421976\/","title":{"rendered":"FREE SPIRIT PUBLISHING Germs Are Not for Sharing (Best Behavior) by Elizabeth Verdick (Paperback) FRE1575421976"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":""},"product_brand":[],"product_cat":[15],"product_tag":[],"class_list":{"0":"post-502456","1":"product","2":"type-product","3":"status-publish","5":"product_cat-uncategorized","6":"sales-flash-overlay","7":"woocommerce-text-align-center","8":"woocommerce-image-align-center","9":"do-quantity-buttons","11":"first","12":"outofstock","13":"sold-individually","14":"purchasable","15":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.teachersparadise.com\/co\/wp-json\/wp\/v2\/product\/502456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teachersparadise.com\/co\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.teachersparadise.com\/co\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.teachersparadise.com\/co\/wp-json\/wp\/v2\/media?parent=502456"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.teachersparadise.com\/co\/wp-json\/wp\/v2\/product_brand?post=502456"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.teachersparadise.com\/co\/wp-json\/wp\/v2\/product_cat?post=502456"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.teachersparadise.com\/co\/wp-json\/wp\/v2\/product_tag?post=502456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}